{"id":2141,"count":1,"description":"","link":"https:\/\/danilodiaz-granados.com\/en\/tag\/le-coucou-new-york\/","name":"Le Coucou New York","slug":"le-coucou-new-york","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Coucou New York Archivos - Danilo D\u00edazgranados Manglano<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Coucou New York Archivos - Danilo D\u00edazgranados Manglano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/danilodiaz-granados.com\/en\/tag\/le-coucou-new-york\/\" \/>\n<meta property=\"og:site_name\" content=\"Danilo D\u00edazgranados Manglano\" \/>\n<meta property=\"og:image\" content=\"https:\/\/danilodiaz-granados.com\/wp-content\/uploads\/2018\/11\/danilo-diaz-granados-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"532\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/tag\\\/le-coucou-new-york\\\/\",\"url\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/tag\\\/le-coucou-new-york\\\/\",\"name\":\"Le Coucou New York Archivos - Danilo D\u00edazgranados Manglano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/tag\\\/le-coucou-new-york\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/tag\\\/le-coucou-new-york\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Coucou New York\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/\",\"name\":\"Danilo D\u00edazgranados Manglano\",\"description\":\"Emprendimiento e innovaci\u00f3n con inversiones de valor\",\"publisher\":{\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/#\\\/schema\\\/person\\\/39af1122d5562bece5428f56fd21909a\"},\"alternateName\":\"Danilo D\u00edazgranados Manglano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/en\\\/#\\\/schema\\\/person\\\/39af1122d5562bece5428f56fd21909a\",\"name\":\"Danilo Diazgranados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Foto-DDGR_Danilo-.png\",\"url\":\"https:\\\/\\\/danilodiaz-granados.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Foto-DDGR_Danilo-.png\",\"contentUrl\":\"https:\\\/\\\/danilodiaz-granados.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Foto-DDGR_Danilo-.png\",\"width\":432,\"height\":432,\"caption\":\"Danilo Diazgranados\"},\"logo\":{\"@id\":\"https:\\\/\\\/danilodiaz-granados.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Foto-DDGR_Danilo-.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Coucou New York Archivos - Danilo D\u00edazgranados Manglano","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Le Coucou New York Archivos - Danilo D\u00edazgranados Manglano","og_url":"https:\/\/danilodiaz-granados.com\/en\/tag\/le-coucou-new-york\/","og_site_name":"Danilo D\u00edazgranados Manglano","og_image":[{"width":532,"height":120,"url":"https:\/\/danilodiaz-granados.com\/wp-content\/uploads\/2018\/11\/danilo-diaz-granados-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/danilodiaz-granados.com\/en\/tag\/le-coucou-new-york\/","url":"https:\/\/danilodiaz-granados.com\/en\/tag\/le-coucou-new-york\/","name":"Le Coucou New York Archivos - Danilo D\u00edazgranados Manglano","isPartOf":{"@id":"https:\/\/danilodiaz-granados.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/danilodiaz-granados.com\/en\/tag\/le-coucou-new-york\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/danilodiaz-granados.com\/en\/tag\/le-coucou-new-york\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/danilodiaz-granados.com\/en\/"},{"@type":"ListItem","position":2,"name":"Le Coucou New York"}]},{"@type":"WebSite","@id":"https:\/\/danilodiaz-granados.com\/en\/#website","url":"https:\/\/danilodiaz-granados.com\/en\/","name":"Danilo D\u00edazgranados Manglano","description":"Emprendimiento e innovaci\u00f3n con inversiones de valor","publisher":{"@id":"https:\/\/danilodiaz-granados.com\/en\/#\/schema\/person\/39af1122d5562bece5428f56fd21909a"},"alternateName":"Danilo D\u00edazgranados Manglano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/danilodiaz-granados.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/danilodiaz-granados.com\/en\/#\/schema\/person\/39af1122d5562bece5428f56fd21909a","name":"Danilo Diazgranados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/danilodiaz-granados.com\/wp-content\/uploads\/2020\/05\/Foto-DDGR_Danilo-.png","url":"https:\/\/danilodiaz-granados.com\/wp-content\/uploads\/2020\/05\/Foto-DDGR_Danilo-.png","contentUrl":"https:\/\/danilodiaz-granados.com\/wp-content\/uploads\/2020\/05\/Foto-DDGR_Danilo-.png","width":432,"height":432,"caption":"Danilo Diazgranados"},"logo":{"@id":"https:\/\/danilodiaz-granados.com\/wp-content\/uploads\/2020\/05\/Foto-DDGR_Danilo-.png"}}]}},"_links":{"self":[{"href":"https:\/\/danilodiaz-granados.com\/en\/wp-json\/wp\/v2\/tags\/2141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/danilodiaz-granados.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/danilodiaz-granados.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/danilodiaz-granados.com\/en\/wp-json\/wp\/v2\/posts?tags=2141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}